{"id":238,"count":45,"description":"","link":"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/","name":"Academia de gin\u00e1stica","slug":"academia-de-ginastica","taxonomy":"property-feature","parent":221,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Academia de gin\u00e1stica Archives | Hansen Im\u00f3veis | Case in vendita Lauro de Freitas, Litoral Norte e Salvador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Academia de gin\u00e1stica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/\" \/>\n<meta property=\"og:site_name\" content=\"Hansen Im\u00f3veis | Case in vendita Lauro de Freitas, Litoral Norte e Salvador\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/property-feature\\\/academia-de-ginastica\\\/\",\"url\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/property-feature\\\/academia-de-ginastica\\\/\",\"name\":\"Academia de gin\u00e1stica Archives | Hansen Im\u00f3veis | Case in vendita Lauro de Freitas, Litoral Norte e Salvador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/property-feature\\\/academia-de-ginastica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/property-feature\\\/academia-de-ginastica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobili\",\"item\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Condominio\",\"item\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/property-feature\\\/condominio-it\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Academia de gin\u00e1stica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/\",\"name\":\"Hansen Im\u00f3veis | Case in vendita Lauro de Freitas, Litoral Norte e Salvador\",\"description\":\"Homes for sale in Lauro de Freitas, Litoral Norte and Salvador\",\"publisher\":{\"@id\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/#organization\",\"name\":\"Hansen Im\u00f3veis LTDA\",\"url\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/property-feature\\\/academia-de-ginastica\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/property-feature\\\/academia-de-ginastica\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Hansen-Imveis-356389241069613\\\/\",\"https:\\\/\\\/www.pinterest.dk\\\/hansenimoveis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCH1v_JXMzDe4Pf4-ZHMaFDg\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hansenimoveis.com\\\/it\\\/property-feature\\\/academia-de-ginastica\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/hansenimoveis.com\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/Hansen-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/hansenimoveis.com\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/Hansen-logo.jpg\",\"width\":283,\"height\":283,\"caption\":\"Hansen Im\u00f3veis LTDA\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Academia de gin\u00e1stica Archives | Hansen Im\u00f3veis | Case in vendita Lauro de Freitas, Litoral Norte e Salvador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/","og_locale":"it_IT","og_type":"article","og_title":"Arquivos Academia de gin\u00e1stica","og_url":"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/","og_site_name":"Hansen Im\u00f3veis | Case in vendita Lauro de Freitas, Litoral Norte e Salvador","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/","url":"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/","name":"Academia de gin\u00e1stica Archives | Hansen Im\u00f3veis | Case in vendita Lauro de Freitas, Litoral Norte e Salvador","isPartOf":{"@id":"https:\/\/hansenimoveis.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/hansenimoveis.com\/it\/"},{"@type":"ListItem","position":2,"name":"Immobili","item":"https:\/\/hansenimoveis.com\/it\/property\/"},{"@type":"ListItem","position":3,"name":"Condominio","item":"https:\/\/hansenimoveis.com\/it\/property-feature\/condominio-it\/"},{"@type":"ListItem","position":4,"name":"Academia de gin\u00e1stica"}]},{"@type":"WebSite","@id":"https:\/\/hansenimoveis.com\/it\/#website","url":"https:\/\/hansenimoveis.com\/it\/","name":"Hansen Im\u00f3veis | Case in vendita Lauro de Freitas, Litoral Norte e Salvador","description":"Homes for sale in Lauro de Freitas, Litoral Norte and Salvador","publisher":{"@id":"https:\/\/hansenimoveis.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hansenimoveis.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/hansenimoveis.com\/it\/#organization","name":"Hansen Im\u00f3veis LTDA","url":"https:\/\/hansenimoveis.com\/it\/","logo":{"@id":"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/#local-main-organization-logo"},"image":{"@id":"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/Hansen-Imveis-356389241069613\/","https:\/\/www.pinterest.dk\/hansenimoveis\/","https:\/\/www.youtube.com\/channel\/UCH1v_JXMzDe4Pf4-ZHMaFDg"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hansenimoveis.com\/it\/property-feature\/academia-de-ginastica\/#local-main-organization-logo","url":"https:\/\/hansenimoveis.com\/wp-content\/uploads\/2014\/06\/Hansen-logo.jpg","contentUrl":"https:\/\/hansenimoveis.com\/wp-content\/uploads\/2014\/06\/Hansen-logo.jpg","width":283,"height":283,"caption":"Hansen Im\u00f3veis LTDA"}]}},"meta_box":{"inspiry_property_feature_icon":[]},"_links":{"self":[{"href":"https:\/\/hansenimoveis.com\/it\/wp-json\/wp\/v2\/property-feature\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hansenimoveis.com\/it\/wp-json\/wp\/v2\/property-feature"}],"about":[{"href":"https:\/\/hansenimoveis.com\/it\/wp-json\/wp\/v2\/taxonomies\/property-feature"}],"up":[{"embeddable":true,"href":"https:\/\/hansenimoveis.com\/it\/wp-json\/wp\/v2\/property-feature\/221"}],"wp:post_type":[{"href":"https:\/\/hansenimoveis.com\/it\/wp-json\/wp\/v2\/property?property-feature=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}